{"id":3972,"date":"2021-03-19T21:00:33","date_gmt":"2021-03-19T21:00:33","guid":{"rendered":"https:\/\/www.spcstuttgart.de\/?page_id=3972"},"modified":"2025-11-04T14:47:49","modified_gmt":"2025-11-04T13:47:49","slug":"hriscanski-dom-cir","status":"publish","type":"page","link":"https:\/\/spcstuttgart.de\/de\/hriscanski-dom-cir\/","title":{"rendered":"Orthodoxes Haus"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3972\" class=\"elementor elementor-3972\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-24d987d e-flex e-con-boxed e-con e-parent\" data-id=\"24d987d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a3b1352 e-con-full e-flex e-con e-child\" data-id=\"a3b1352\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89ce6e1 elementor-widget elementor-widget-text-editor\" data-id=\"89ce6e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u201eEr ist wie ein Baum, der am Wasser gepflanzt ist und am Bach seine Wurzeln ausstreckt: Er hat nichts zu f\u00fcrchten, wenn Hitze kommt; seine Bl\u00e4tter bleiben gr\u00fcn; auch in einem trockenen Jahr ist er ohne Sorge, unabl\u00e4ssig bringt er seine Fr\u00fcchte.\u201c <\/strong>(Jer 17,8)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf46c32 elementor-widget elementor-widget-text-editor\" data-id=\"bf46c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das wichtigste Merkmal eines christlichen und orthodoxen Domizils ist, dass dieses gesegnet ist. Dar\u00fcber hinaus sollte ein christliches Zuhause folgendes haben: eine Ikone (serbisch: Ikona), eine \u00d6lkerze (serbisch: Kandilo), einen Kerzenhalter sowie eine Kerze (serbisch: \u010cirak i Sve\u0107a), einen Holzstempel f\u00fcr das Slava-Brot (serbisch: Slovo, Prosfornik, Anafornik), einen Weihrauchfass (serbisch: Kadionica), Basilikum (serbisch: Bosiljak),  Weihrauch (serbisch: Tamjan), die Heilige Schrift (serbisch: Sveto Pismo) und ein Gebetbuch (serbisch: Molitvenik).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82c32b6 e-flex e-con-boxed e-con e-parent\" data-id=\"82c32b6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d1b02bd e-con-full e-flex e-con e-child\" data-id=\"d1b02bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f686e34 elementor-widget elementor-widget-heading\" data-id=\"f686e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Haussegnung (serbisch: Osve\u0107enje doma)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7ba1d0 elementor-widget elementor-widget-text-editor\" data-id=\"a7ba1d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Wenn ein Haus oder eine Wohnung gebaut, gestrichen, versch\u00f6nert und eingerichtet wird und wenn die Familie anf\u00e4ngt, darin zu leben, ist es notwendig, diesen Wohnort zu segnen. Diese Segnung wird vom zust\u00e4ndigen Pfarrer durchgef\u00fchrt. Die Segnung wird wie folgt durchgef\u00fchrt:\nDer zust\u00e4ndige Pfarrer wird gerufen, mancherorts auch der Pate. In dem feierlichen Raum, in dem sich die Ikonen befinden, wird ein mit einer Tischdecke bedeckter Tisch aufgestellt und auf dem Tisch folgendes platziert: eine Kerze, ein Weihrauchfass, Weihrauch, eine Sch\u00fcssel mit Wasser, Basilikum, eine Sch\u00fcssel mit etwas Mehl, ein Glas \u00d6l, vier kleine Kerzen und ein kleiner Stab, der an einem Ende in Watte gewickelt ist, mit dem die W\u00e4nde mit \u00d6l gesalbt werden. Die Kerzen werden w\u00e4hrend der Segnung angez\u00fcndet und an die W\u00e4nde der Wohnung angeklebt. Die Segnung wird zu jeder Tageszeit durchgef\u00fchrt. \t\nIn den Gebeten betet der Pfarrer f\u00fcr den Fortschritt, f\u00fcr die Gesundheit und das Gl\u00fcck des Domizils, insbesondere der Kinder, f\u00fcr Harmonie, Liebe, Verst\u00e4ndnis und f\u00fcr jedes Gute, das Christen zu Gott beten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7037a64 e-flex e-con-boxed e-con e-parent\" data-id=\"7037a64\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-879ab4a e-con-full e-flex e-con e-child\" data-id=\"879ab4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d909ee5 elementor-widget elementor-widget-heading\" data-id=\"d909ee5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ikone (serbisch: Ikona)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91144b9 elementor-widget elementor-widget-text-editor\" data-id=\"91144b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Jede christliche Wohnung sollte eine Ikone seines Schutzpatrons besitzen. Die Ikone wird im feierlichsten Raum, im Ess- oder Wohnzimmer, immer an der \u00f6stlichen Wand aufgeh\u00e4ngt.\nNeben der Ikone des Schutzpatrons ist es w\u00fcnschenswert, dass sich auch die Ikone Christi des Erl\u00f6sers und die Ikone der Gottesmutter befindet. Es kann auch die Ikone eines anderen Heiligen, der in der Familie besonders respektiert wird, z.B.: des Heiligen Sava aufgeh\u00e4ngt werden. Die Wand, an der die Ikonen h\u00e4ngen, sollte frei sein von anderen Gem\u00e4lden, Postern usw. \nDie orthodoxe Kirche hat ihre eigenen Regeln in der Ikonographie. Der byzantinische Stil ist in der Ikonenmalerei am st\u00e4rksten vertreten. Leider werden auch Ikonen auf unseren M\u00e4rkten verkauft, so dass auch hier beispielloser Kitsch herrscht und das auf den Ikonen dargestellte, eher wie eine Karikatur als wie ein Heiliger aussieht. Deshalb wird empfohlen, Ikonen in Kirchen zu kaufen. Wenn die Ikone gekauft wird, wird sie in die Kirche dem Pfarrer zur Weihe gebracht. Mancherorts wird praktiziert, dass die Ikone einige Wochen in der Kirche bleibt. Die geweihte Ikone wird anschlie\u00dfend an dem passenden Ort aufgeh\u00e4ngt. Es w\u00e4re gut, wenn sich vor der Ikone ein kleiner Tisch befinden w\u00fcrde, auf dem alle oben genannten Dinge und Objekte stehen w\u00fcrden.\nAlle christlichen Riten und Gebete werden zuhause vor der Ikone durchgef\u00fchrt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7078bf e-flex e-con-boxed e-con e-parent\" data-id=\"b7078bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c8f477 e-con-full e-flex e-con e-child\" data-id=\"9c8f477\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f3dfb5b elementor-widget elementor-widget-heading\" data-id=\"f3dfb5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00d6lkerze (serbisch: Kandilo)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8ee1f4 elementor-widget elementor-widget-text-editor\" data-id=\"c8ee1f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die \u00d6lkerze wird vor der Ikone positioniert. Sie wird in der Regel am Vorabend und an jedem Feiertag sowie an jedem Sonntag angez\u00fcndet. Sie kann aber auch st\u00e4ndig brennen.\nDie \u00d6lkerze wird normalerweise von der Hausfrau angez\u00fcndet und gepflegt. Die Flamme der \u00d6lkerze symbolisiert das Licht der Lehre Christi und das Licht des Lebens des Heiligen, vor dem die Kerze angez\u00fcndet wird. Gleichzeitig werden alle im Haus daran erinnert, dass auch sie ein helles und sauberes Leben f\u00fchren sollten. Diejenigen, die eine \u00d6lkerze in ihrer Wohnung haben, wissen, welche einzigartige spirituelle Atmosph\u00e4re an Feier- und Sonntagen durch die flackernde Flamme erzeugt wird. Dies ist besonders in die Seele des Kindes eingraviert und bleibt eine sch\u00f6ne Erinnerung von der Kindheit bis zum Lebensende.\n Diese Atmosph\u00e4re ist eine unersch\u00f6pfliche Inspiration f\u00fcr alle k\u00fcnstlerischen und poetischen Seelen. Viele gro\u00dfartige Werke wurden geschaffen, inspiriert von diesem flackernden, unvergesslichen Licht und Schattenspiel der \u00d6lkerze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a07e173 e-flex e-con-boxed e-con e-parent\" data-id=\"a07e173\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-158e42f e-con-full e-flex e-con e-child\" data-id=\"158e42f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7a7f559 elementor-widget elementor-widget-heading\" data-id=\"7a7f559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kerzenhalter und Kerze (serbisch: \u010cirak i Sve\u0107a)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34aeceb elementor-widget elementor-widget-text-editor\" data-id=\"34aeceb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ohne eine Kerze kann im Haus kein Ritus oder Gebet durchgef\u00fchrt werden. Der Kerzenhalter und die Kerze stehen im Haus an einem besonderen Platz und werden immer vor dem Gebet angez\u00fcndet.\nDer Hausherr z\u00fcndet die Kerze folgenderma\u00dfen an: Zuerst bekreuzigt er sich, erw\u00e4hnt Gott und seinen Schutzpatron, k\u00fcsst und z\u00fcndet eine Kerze an. Die Slava-Kerze wird mit Hilfe von Wein gel\u00f6scht, die kleinere Kerze wird entweder ausgeblasen oder der brennende Docht mit einem feuchten Daumen und Zeigefinger zusammengedr\u00fcckt. Die Flamme der Kerze hat die gleiche Symbolik wie die der \u00d6lkerze.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44aa021 e-flex e-con-boxed e-con e-parent\" data-id=\"44aa021\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1c5048d e-con-full e-flex e-con e-child\" data-id=\"1c5048d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-59ec800 elementor-widget elementor-widget-heading\" data-id=\"59ec800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Holzstempel f\u00fcr das Slava-Brot (serbisch: Slovo, Prosfornik, Anafornik)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-737a246 elementor-widget elementor-widget-text-editor\" data-id=\"737a246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Holzstempel wird in das Slava-Brot gedr\u00fcckt. Auch der Stempel wird in die Kirche zur Weihung gebracht. \t\nFolgende Buchstaben sind auf dem Stempel eingraviert: \u0418\u0421 \u0425\u0421 \u041d\u0418 \u041a\u0410 \u2013 bedeutet: Jesus Christus siegt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-913c137 elementor-widget elementor-widget-heading\" data-id=\"913c137\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Basilikum (serbisch: Bosiljak)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75492f2 elementor-widget elementor-widget-text-editor\" data-id=\"75492f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Basilikum ist eine aromatische Pflanze mit einem angenehmen Duft, die in G\u00e4rten und Blumenbeeten angebaut wird. Das Basilikum wird gesammelt, zu einem Blumenstrau\u00df gefaltet, gebunden und getrocknet. Es wird das ganze Jahr \u00fcber so aufbewahrt und herausgenommen, wenn der Pfarrer das Wasser weiht, um die Haushaltsmitglieder damit zu betr\u00e4ufeln. Basilikum und sein angenehmer Duft symbolisieren den Segen des Heiligen Geistes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-407b3f4 e-flex e-con-boxed e-con e-parent\" data-id=\"407b3f4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-578a0ec e-con-full e-flex e-con e-child\" data-id=\"578a0ec\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47a156a elementor-widget elementor-widget-heading\" data-id=\"47a156a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weihrauchfass, Glut und Weihrauch (serbisch: Kadionica, \u017ear und tamjan)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d928a3 elementor-widget elementor-widget-text-editor\" data-id=\"0d928a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das Weihrauchfass f\u00fcr den h\u00e4uslichen Gebrauch ist normalerweise aus Erde oder Metall gefertigt und hat verschiedene Formen, die im Einklang mit dem christlichen Geist stehen.\nIn das Weihrauchfass wird ein St\u00fcck Holzglut gestellt (Kohleglut riecht unangenehm) und auf diese Holzglut wird Weihrauch gelegt, wodurch ein duftender und angenehmer Geruch verbreitet wird. Da es in St\u00e4dten oft keine Holzglut gibt, wird ein spezielles, rundes Brikett verwendet, welches zugleich sehr praktisch ist.\nDas Weihrauchfass und die Holzglut darin symbolisieren unsere leidenschaftliche Liebe zum Glauben und die W\u00e4rme unserer christlichen Seele. Der Duft von Weihrauch symbolisiert den Segen des Heiligen Geistes. Das Weihrauchfass wird bei jedem Gebet benutzt. Der Hausherr beweihr\u00e4uchert, indem er das Weihrauchfass in der rechten Hand h\u00e4lt und damit Kreuzzeichen macht. Als erstes werden \u00c4ltere beweihr\u00e4uchert, dann J\u00fcngere. Auch das Weihrauchfass sollte an einem besonderen Platz aufbewahrt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d68fe0 e-flex e-con-boxed e-con e-parent\" data-id=\"4d68fe0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-11f1c0a e-con-full e-flex e-con e-child\" data-id=\"11f1c0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1519829 elementor-widget elementor-widget-heading\" data-id=\"1519829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Heilige Schrift \u2013 Bibel (serbisch: Sveto Pismo \u2013 Biblija)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4492a68 elementor-widget elementor-widget-text-editor\" data-id=\"4492a68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Man kann sich in der christlichen Welt kein Haushalt ohne die Heilige Schrift vorstellen.\nIm westlichen Christentum gibt es in jedem Hotelzimmer in der N\u00e4he des Kopfteils die Heilige Schrift, die dem Gast zur Verf\u00fcgung steht, damit er eine Passage aus diesem heiligen Buch lesen und so geistig gest\u00e4rkt werden kann. Leider ist die Heilige Schrift bei uns in in den Haushalten kein sehr verbreitetes Buch.\nDeshalb sollte jeder Haushalt danach streben, dieses Buch zu besitzen. Nat\u00fcrlich sollten die Pfarrer und die Kirche am meisten daran arbeiten, vor allem wegen unserer Kinder und der Jugend. Ohne die Bibel kann man weder Geschichte noch Philosophie, Kunst, Literatur, Musik, somit die gesamte Zivilisation verstehen.\nDie Bibel oder die Heilige Schrift (dies sind die Namen f\u00fcr dasselbe Buch) hat nicht nur einen kulturellen, sondern vor allem einen spirituellen, betenden, religi\u00f6sen und p\u00e4dagogischen Charakter.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb03dd7 e-flex e-con-boxed e-con e-parent\" data-id=\"eb03dd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-342b213 e-con-full e-flex e-con e-child\" data-id=\"342b213\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-045f9db elementor-widget elementor-widget-heading\" data-id=\"045f9db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gebetbuch (serbisch: Molitvenik)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43053ae elementor-widget elementor-widget-text-editor\" data-id=\"43053ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ein Gebetbuch ist normalerweise eine kleines Taschenbuch, in dem sich Gebete f\u00fcr verschiedene Anl\u00e4sse, Bed\u00fcrfnisse und Zeiten im Leben eines Christen befinden. Es w\u00e4re w\u00fcnschenswert, wenn jeder Haushalt dieses Buch h\u00e4tte. \nDas Gebetbuch steht vor der Ikone. Bei Hausgebeten werden Gebete aus dem Gebetbuch gelesen. Sie werden vom Hausherrn und vielleicht von einem der j\u00fcngeren Haushaltsmitglieder gelesen, die eine angenehme und freundliche Stimme haben. W\u00e4hrend die Gebete gelesen werden, stehen alle, h\u00f6ren aufmerksam zu und beten in sich.\nWichtige Gebete wie: Vater unser, Gebet zur Allheiligen Gottesgeb\u00e4rerin, Allheilige Dreiheit, Glaubensbekenntnis und Himmlischer K\u00f6nig sollte jeder Christ auswendig lernen, damit er sie auch au\u00dferhalb seines Hauses sprechen kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36ca88e e-flex e-con-boxed e-con e-parent\" data-id=\"36ca88e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-53d0304 e-con-full e-flex e-con e-child\" data-id=\"53d0304\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f9d3f53 elementor-widget elementor-widget-heading\" data-id=\"f9d3f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hausgebete (Serbisch: Doma\u0107a molitva)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48e3fbc elementor-widget elementor-widget-text-editor\" data-id=\"48e3fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Zus\u00e4tzlich zu den gemeinsamen Gottesdiensten in der Kirche, an denen alle Bewohner eines Dorfes oder einer Stadt teilnehmen, sollte jedes Haus und jede Familie ein eigenes Haus-gebet haben.\n\tJede Familie stellt eine Art Kirche im Kleinen dar. Es w\u00e4re gut, wenn diese Hausgebete vor und nach jeder Mahlzeit, jeden Abend, wenn die Familie zu Bett geht, und jeden Morgen gesprochen werden w\u00fcrden. Aber wenn nicht jeden Tag, ist es obligatorisch, am Vorabend von Sonn- und Feiertagen zu Hause zu beten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be07a01 e-con-full e-flex e-con e-child\" data-id=\"be07a01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-803068e elementor-widget elementor-widget-heading\" data-id=\"803068e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie wird zu Hause gebetet?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-513156d elementor-widget elementor-widget-text-editor\" data-id=\"513156d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Der Hausherr stellt sich vor die Ikone hin, vor die Hausfrau bereits die \u00d6lkerze angez\u00fcndet hat. Hinter ihm stehen alle anderen Haushaltsmitglieder. Er bekreuzigt sich, z\u00fcndet eine Kerze an, nimmt das Weihrauchfass, setzt Weihrauch auf die Holzglut, beweihr\u00e4uchert zuerst die Ikonen, dann sich selbst, seine Haushaltsmitglieder und \u00fcberreicht das Weihrauchfass einer j\u00fcngeren Person, die dann das ganze Haus beweihr\u00e4uchert. Dann liest der Hausherr oder einer der J\u00fcngeren die Gebete aus dem Gebetbuch oder die Passagen aus der Heiligen Schrift oder die Gebete, die er auswendig kennt: Vater unser, Gebet zur Allheiligen Gottesgeb\u00e4rerin, Allheilige Dreiheit usw. Nach dem Gebet sagt der Hausherr: M\u00f6gen die Gebete der Gesundheit dienen, und die J\u00fcngeren sprechen: Amen, M\u00f6ge Gott uns helfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60b567d e-flex e-con-boxed e-con e-parent\" data-id=\"60b567d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c2aeac8 e-con-full e-flex e-con e-child\" data-id=\"c2aeac8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a435ac0 elementor-widget elementor-widget-heading\" data-id=\"a435ac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pers\u00f6nliches Gebet (serbisch: Li\u010dna molitva)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-429b984 elementor-widget elementor-widget-text-editor\" data-id=\"429b984\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Zus\u00e4tzlich zum gemeinsamen Gebet hat jeder Christ sein eigenes pers\u00f6nliches, intimes Gebet. Vor jeder Arbeit, vor und nach dem Essen, beim Zubettgehen und morgens beim Aufstehen, in schwierigen sowie in guten Zeiten, sollte man sich immer bekreuzen und das entsprechende Gebet aufrichtig aus der Tiefe der Seele lesen, beten und Gott danken.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f6c293 e-flex e-con-boxed e-con e-parent\" data-id=\"7f6c293\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-58d108c e-con-full e-flex e-con e-child\" data-id=\"58d108c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dfed61 elementor-widget elementor-widget-heading\" data-id=\"2dfed61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das Fasten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b5ed6 elementor-widget elementor-widget-text-editor\" data-id=\"c5b5ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Neben dem Gebet ist das Fasten einer der wichtigsten Inhalte im Leben eines jeden Christen. Fasten ist bekanntlich die Abstinenz von Lebensmitteln tierischer Herkunft und \u00fcberm\u00e4\u00dfigem Essen und Trinken. Die Essenz des Fastens liegt jedoch nicht darin keine Lebensmittel tierischer Herkunft zu essen. Das wichtigste Merkmal des Fastens ist, auf b\u00f6se und schlechte Taten zu verzichten, gute Taten zu verrichten und sich in Tugend, Vergebung, Bescheidenheit und Demut zu \u00fcben, um alle k\u00f6rperlichen Leidenschaften einzud\u00e4mmen, die das geistige Leben eines jeden Christen zerst\u00f6ren. Fasten ist also nicht nur k\u00f6rperliche Abstinenz, sondern auch geistige. Die Kirche schreibt vier Fastenzeiten pro Jahr vor: Die Gro\u00dfe Fastenzeit und die Karwoche, Apostelfasten, Muttergottesfasten und die Weihnachtsfastenzeit. Diese Fastenzeiten werden als mehrt\u00e4gige Fastenzeiten bezeichnet. Die eint\u00e4gigen Fastentage finden jeden Mittwoch und Freitag statt, au\u00dfer in den fastenfreien Zeiten (die im Kalender abgedruckt sind) und: Kreuztag vor Theophanie (18. Januar), Enthauptung Johannes\u2018 des T\u00e4ufers (11. September) und Allgemeine Erh\u00f6hung des kostbaren und lebensspendenden Kreuzes (27. September). An diesen Tagen werden Lebensmittel tierischer Herkunft nicht gegessen, d.h. kein Fleisch, kein Schmalz, kein Fisch, keine Milchprodukte, keine Eier, usw. Es werden also vegane Speisen konsumiert, die mit Speise\u00f6l zubereitet sind. Das Fasten kann mit dem Segen des zust\u00e4ndigen Pfarrers etwas strenger sein, dieses Fasten wird Fasten \"auf dem Wasser\" genannt, d.h. ohne den Verzehr von \u00d6l. Alles, was aus pflanzlichen Lebensmitteln zubereitet wird, wird \"auf Wasser\" zubereitet (gekochte Bohnen, Kartoffeln, Karotten, Erbsen usw.) und wird nicht mit \u00d6l angebraten. An Karfreitag wird am strengsten gefastet, d.h. \"auf Wasser\".\n\tFolgendes ist zu erw\u00e4hnen: F\u00e4llt der Tag der Feier des Schutzpatrons (serbisch: Slava) im Zeitraum der mehr- oder eint\u00e4gigen Fastenzeiten, also auch mittwochs oder freitags, so m\u00fcssen Speisen vegan zubereitet werden, wobei in den meisten F\u00e4llen auch Fisch gegessen werden darf. Das gleiche gilt auch f\u00fcr Trauerfeiern, egal ob in dem Haus gefastet wird oder nicht. Einige Gl\u00e4ubige fasten nur in der ersten und letzten Fastenwoche und glauben, dass dies genug ist. Dies stellt das gleiche dar, wie eine Br\u00fccke \u00fcber einen Fluss zu bauen, jedoch nur auf den beiden Seiten des Ufers zu bauen und die Mitte unbebaut zu lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201e\u0408\u0435\u0440 \u045b\u0435 \u0431\u0438\u0442\u0438 \u043a\u0430\u043e \u0434\u0440\u0432\u043e \u0443\u0441\u0430\u0452\u0435\u043d\u043e \u043a\u0440\u0430\u0458 \u0432\u043e\u0434\u0435 \u0438 \u043a\u043e\u0458\u0435 \u043d\u0438\u0437 \u043f\u043e\u0442\u043e\u043a \u043f\u0443\u0448\u0442\u0430 \u0436\u0438\u043b\u0435 \u0441\u0432\u043e\u0458\u0435, \u043a\u043e\u0458\u0435 \u043d\u0435 \u043e\u0441\u0435\u045b\u0430 \u043a\u0430\u0434 \u0434\u043e\u0452\u0435 \u043f\u0440\u0438\u043f\u0435\u043a\u0430, \u043d\u0435\u0433\u043e \u043c\u0443 \u0441\u0435 \u043b\u0438\u0441\u0442 \u0437\u0435\u043b\u0435\u043d\u0438, \u0438 \u0441\u0443\u0448\u043d\u0435 \u0433\u043e\u0434\u0438\u043d\u0435 \u043d\u0435 \u0431\u0440\u0438\u043d\u0435 \u0441\u0435 \u0438 \u043d\u0435 \u043f\u0440\u0435\u0441\u0442\u0430\u0458\u0435 \u0440\u0430\u0452\u0430\u0442\u0438 \u0440\u043e\u0434\u201c (\u0408\u0435\u0440. 17,8) \u041d\u0430\u0458\u0431\u0438\u0442\u043d\u0438\u0458\u0435 \u043e\u0431\u0435\u043b\u0435\u0436\u0458\u0435 \u0458\u0435\u0434\u043d\u043e\u0433 \u0445\u0440\u0438\u0448\u045b\u0430\u043d\u0441\u043a\u043e\u0433 \u0438 \u043f\u0440\u0430\u0432\u043e\u0441\u043b\u0430\u0432\u043d\u043e\u0433 \u0434\u043e\u043c\u0430, \u043f\u0440\u0435 \u0441\u0432\u0435\u0433\u0430, \u0458\u0435\u0441\u0442\u0435 \u0434\u0430 \u0458\u0435 \u0434\u043e\u043c \u043e\u0441\u0432\u0435\u045b\u0435\u043d. \u041f\u043e\u0440\u0435\u0434 \u0442\u043e\u0433\u0430, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"disabled","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3972","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/comments?post=3972"}],"version-history":[{"count":21,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3972\/revisions"}],"predecessor-version":[{"id":13720,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3972\/revisions\/13720"}],"wp:attachment":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/media?parent=3972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}