{"id":3905,"date":"2021-03-19T19:23:08","date_gmt":"2021-03-19T19:23:08","guid":{"rendered":"https:\/\/www.spcstuttgart.de\/?page_id=3905"},"modified":"2025-11-30T09:25:13","modified_gmt":"2025-11-30T08:25:13","slug":"dobrotvorni-rad","status":"publish","type":"page","link":"https:\/\/spcstuttgart.de\/de\/dobrotvorni-rad\/","title":{"rendered":"Wohlt\u00e4tigkeitsarbeit"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3905\" class=\"elementor elementor-3905\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-46bbf077 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46bbf077\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-641be98\" data-id=\"641be98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23fe0927 elementor-widget elementor-widget-theme-site-logo elementor-widget-image\" data-id=\"23fe0927\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-site-logo.default\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/spcstuttgart.de\/de\">\n\t\t\t<img alt=\"\" fetchpriority=\"high\" decoding=\"async\" width=\"334\" height=\"400\" src=\"https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/Srpska-pravoslavna-crkva-logo-1-e1617143735577.png\" class=\"attachment-full size-full wp-image-246\" srcset=\"https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/Srpska-pravoslavna-crkva-logo-1-e1617143735577.png 1x, https:\/\/www.spcstuttgart.de\/wp-content\/uploads\/2021\/01\/cropped-Srpska-pravoslavna-crkva-logo-1-e1612076992899-1.png 2x\" sizes=\"(max-width: 334px) 100vw, 334px\" \/>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7964562e\" data-id=\"7964562e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-183506a5 elementor-nav-menu__align-end elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"183506a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Men\u00fc\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-183506a5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-7423\"><a href=\"https:\/\/spcstuttgart.de\/de\/\" class=\"elementor-item menu-link\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7424\"><a href=\"https:\/\/spcstuttgart.de\/de\/istorija-crkve\/\" class=\"elementor-item menu-link\">Geschichte der Kirche<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8504\"><a href=\"https:\/\/spcstuttgart.de\/de\/novosti\/\" class=\"elementor-item menu-link\">Nachrichten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7425\"><a href=\"https:\/\/spcstuttgart.de\/de\/kontakt\/\" class=\"elementor-item menu-link\">Kontakt<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-183506a5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-7423\"><a href=\"https:\/\/spcstuttgart.de\/de\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7424\"><a href=\"https:\/\/spcstuttgart.de\/de\/istorija-crkve\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Geschichte der Kirche<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-8504\"><a href=\"https:\/\/spcstuttgart.de\/de\/novosti\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Nachrichten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-7425\"><a href=\"https:\/\/spcstuttgart.de\/de\/kontakt\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-111cf2ac\" data-id=\"111cf2ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62ffac0c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"62ffac0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-church\" viewbox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M464.46 246.68L352 179.2V128h48c8.84 0 16-7.16 16-16V80c0-8.84-7.16-16-16-16h-48V16c0-8.84-7.16-16-16-16h-32c-8.84 0-16 7.16-16 16v48h-48c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h48v51.2l-112.46 67.48A31.997 31.997 0 0 0 160 274.12V512h96v-96c0-35.35 28.65-64 64-64s64 28.65 64 64v96h96V274.12c0-11.24-5.9-21.66-15.54-27.44zM0 395.96V496c0 8.84 7.16 16 16 16h112V320L19.39 366.54A32.024 32.024 0 0 0 0 395.96zm620.61-29.42L512 320v192h112c8.84 0 16-7.16 16-16V395.96c0-12.8-7.63-24.37-19.39-29.42z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d73216 elementor-widget elementor-widget-heading\" data-id=\"17d73216\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjI3MzIiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">Gottesdienste<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55ab98f9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55ab98f9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ac912e4\" data-id=\"7ac912e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52368373 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52368373\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7bffbffb\" data-id=\"7bffbffb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54bb1f25 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"54bb1f25\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wohlt\u00e4tigkeitsarbeit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18a2388 elementor-widget elementor-widget-text-editor\" data-id=\"18a2388\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>\u201eDann wird der K\u00f6nig denen auf der rechten Seite sagen: Kommt her, die ihr von meinem Vater gesegnet seid, nehmt das Reich in Besitz, das seit der Erschaffung der Welt f\u00fcr euch bestimmt ist. Denn ich war hungrig und ihr habt mir zu essen gegeben; ich war durstig und ihr habt mir zu trinken gegeben; ich war fremd und obdachlos und ihr habt mich aufgenommen; ich war nackt und ihr habt mir Kleidung gegeben; ich war krank und ihr habt mich besucht; ich war im Gef\u00e4ngnis und ihr seid zu mir gekommen\u201c<\/strong> (Mt. 25, 34-36).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a08ae8e elementor-widget elementor-widget-text-editor\" data-id=\"a08ae8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Die Frage der Gnade gegen\u00fcber dem N\u00e4chsten (wohlt\u00e4tige und humanit\u00e4re Arbeit) ist in der Kirche keine Nebensache, sondern etwas, was das spirituelle Leben eines jeden orthodoxen Christen sehr betrifft und was die menschliche Erl\u00f6sung direkt beeinflusst. \nUnsere heilige, allumfassende und Apostolische Kirche ist seit der Apostolischen Zeit und w\u00e4hrend ihrer gesamten Geschichte bem\u00fcht, sich um diejenigen zu k\u00fcmmern, die Hilfe brauchen, unabh\u00e4ngig davon wer sie sind.<\/p><p style=\"text-align: center;\">Seit der Gr\u00fcndung unserer Kirchengemeinschaft im Jahr 1971 versucht die Kirche, auf die Bed\u00fcrfnisse und Probleme ihrer Gl\u00e4ubigen zu reagieren, mit denen sie konfrontiert sind, beginnend mit der ersten Migration unserer Bev\u00f6lkerung aus dem ehemaligen Jugoslawien in dieses Gebiet.<\/p><p style=\"text-align: center;\">Mit dem Beginn der Krise im ehemaligen Jugoslawien in den neunziger Jahren besteht ein gro\u00dfer Bedarf an humanit\u00e4rer und gemeinn\u00fctziger Arbeit, weshalb w\u00e4hrend des gesamten Jahrzehnts unsere Kirchengemeinschaft humanit\u00e4re Hilfe f\u00fcr sozial gef\u00e4hrdete Gruppen in der Heimat und in der Region leistete. Nach dem Ende der Kriege richtete die Kirchengemeinschaft ihre Aktivit\u00e4ten darauf aus, den leidenden Menschen im Kosovo und Metohija, dem jahrhundertealten serbischen Heiligtum und der Wiege der serbischen Kultur und Spiritualit\u00e4t zu helfen. Zu Beginn des 21. Jahrhunderts startet die mittlerweile schon traditionelle Aktion der Sammlung von P\u00e4ckchen f\u00fcr Kinder aus dem Kosovo und Metohija, welche bis heute andauert. In den letzten Jahren und mit dem Auftreten schwerwiegender Wetterkatastrophen in der Heimat (\u00dcberschwemmungen, Br\u00e4nde und Erdbeben) beteiligt sich unsere Kirchengemeinschaft aktiv am Sammeln und Senden von materieller und finanzieller Hilfe f\u00fcr Menschen aus betroffenen Gebieten.<\/p><p style=\"text-align: center;\">Au\u00dferdem f\u00fchrt die Kirche in den den letzten Jahren vermehrt Spendenaktionen durch, um aufgrund des zunehmenden und kostenintensiven Behandlungsbedarfs unserer Kinder mit seltenen Krebsarten, die in Krankenh\u00e4usern in Stuttgart und T\u00fcbingen nach Erl\u00f6sung und Hoffnung auf Leben suchen und Gott sei Dank diese auch finden, zu helfen. Den Betroffenen wird sowohl finanziell als auch durch die Bereitstellung von Unterk\u00fcnften f\u00fcr die Familienmitglieder der Erkrankten sowie beim \u00dcbersetzen von Befunden vom Deutschen ins Serbische geholfen.<\/p><p style=\"text-align: center;\">Dar\u00fcber hinaus ist ein unverzichtbarer Bestandteil der Wohlt\u00e4tigkeitsarbeit die Priesterschaft, welche zus\u00e4tzlich zu ihrer pastoralen Arbeit versucht, Menschen mit verschiedenen Krankheiten psychosoziale Unterst\u00fctzung zu leisten, indem sie sie in Krankenh\u00e4usern und in Gesundheitseinrichtungen besucht, sowie zahlreiche andere Formen des sozialen Dienstes aus\u00fcbt.\n\tDie Zeit, in der wir leben, ist eine Zeit gro\u00dfer sozialer Unterschiede und Ungerechtigkeiten. Es gibt eine gro\u00dfe Anzahl armer Leute. Die R\u00fcckkehr unseres Volkes zum Glauben und zu spirituellen Werten soll von gn\u00e4digen Taten und gemeinn\u00fctziger Arbeit begleitet werden.\n\tDie Heilige Schrift, die Apostolische Tradition und die Geschichte der Kirche zeugen von der Notwendigkeit und Bedeutung gemeinn\u00fctziger Aktivit\u00e4ten und gn\u00e4diger Taten. \nBeispiele aus der j\u00fcngeren Vergangenheit zeigen, dass das soziale Dienen auch unter schwierigsten Umst\u00e4nden m\u00f6glich sind. Aber vorher muss jeder von sich selbst ausgehen und mit den Leiden seiner Mitmenschen in seinem Herzen mitf\u00fchlen und nicht vergessen, dass jeder Mensch unser N\u00e4chster ist, weil wir alle Kinder Gottes sind. Mit einem solchen Ansatz wird praktisch jede gemeinn\u00fctzige Handlung von selbst kommen.<\/p><p style=\"text-align: center;\">Aus diesem Grund gibt es in unserer Kirchengemeinschaft einen Humanit\u00e4ren Fond, mit dessen Mitteln die Kirche bestrebt ist, so weit wie m\u00f6glich auf die wachsenden Bed\u00fcrfnisse ihrer Gl\u00e4ubigen und derer, die Hilfe ben\u00f6tigen, sowie auf Sie alle zu reagieren. Jeder, der die Kirche bei dieser Arbeit unterst\u00fctzen will, kann einen Beitrag bezahlen an:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd9dd6 elementor-widget elementor-widget-text-editor\" data-id=\"7fd9dd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Serbische Orthodoxe Kirche f<\/strong><strong>\u00fcr W\u00fcrttemberg in Stuttgart e.V.<\/strong><\/p><p>Evangelische Bank<br \/><strong>IBAN: <\/strong>DE82 5206 0410 0200 4158 55<br \/><strong>BIC: <\/strong>GENODEF1EK1<br \/><strong>Verwendungszweck: <\/strong>Humanit\u00e4re Hilfe Fond<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b32042 elementor-widget elementor-widget-text-editor\" data-id=\"5b32042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>\u201eDarauf wird der K\u00f6nig ihnen antworten: Amen, ich sage euch: Was ihr f\u00fcr einen meiner geringsten Br\u00fcder getan habt, das habt ihr mir getan.\u201c<\/strong> (Mt. 25, 40).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f6d910a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f6d910a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7094c5fc\" data-id=\"7094c5fc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4802ddb5 elementor-widget elementor-widget-image\" data-id=\"4802ddb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img alt=\"\" decoding=\"async\" width=\"380\" height=\"400\" src=\"https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/cropped-Srpska-pravoslavna-crkva-logo-1-e1612076992899.png\" class=\"attachment-large size-large wp-image-251\" srcset=\"https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/cropped-Srpska-pravoslavna-crkva-logo-1-e1612076992899.png 380w, https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/cropped-Srpska-pravoslavna-crkva-logo-1-e1612076992899-285x300.png 285w, https:\/\/spcstuttgart.de\/wp-content\/uploads\/2021\/01\/cropped-Srpska-pravoslavna-crkva-logo-1-e1612076992899-11x12.png 11w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b29ac7c elementor-widget elementor-widget-heading\" data-id=\"6b29ac7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kirche der Synaxis der Serbischen Heiligen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2a38d2 elementor-widget elementor-widget-heading\" data-id=\"e2a38d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\"> M\u00f6hringer Str. 81A, 70199 Stuttgart<\/h5>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3e5b9b83\" data-id=\"3e5b9b83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-725801d4 elementor-hidden-desktop elementor-hidden-tablet elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"725801d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8815fc elementor-widget elementor-widget-heading\" data-id=\"6b8815fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kontakt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-580f47b2 elementor-widget elementor-widget-text-editor\" data-id=\"580f47b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">M\u00f6hringer Str. 81A, 70199 Stuttgart \u2013 Heslach\u00a0<\/p><p style=\"text-align: center;\">Tel: 0711\/964 0020<br \/>Fax: 0711964 0021<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97b0d5d elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"97b0d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-a3020bb\" href=\"https:\/\/www.facebook.com\/profile.php?id=100016349493947\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-e0346c4\" href=\"https:\/\/www.instagram.com\/spc_stuttgart?igsh=YjlrZmR3bGZhMTBu\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-ff89df2\" href=\"https:\/\/www.youtube.com\/@SPCSTUTGART\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-490b06f0\" data-id=\"490b06f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cb625e elementor-hidden-desktop elementor-hidden-tablet elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2cb625e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6caea45c elementor-widget elementor-widget-heading\" data-id=\"6caea45c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Navigation website<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c3b5f47 elementor-nav-menu__text-align-center elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"5c3b5f47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-5c3b5f47\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-4274\"><a href=\"https:\/\/spcstuttgart.de\/de\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Startseite<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4272\"><a href=\"https:\/\/spcstuttgart.de\/de\/istorija-crkve\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Geschichte der Kirche<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-4845\"><a href=\"#bogosluzenja\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Gottesdienste<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8618\"><a href=\"#novosti\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\">Nachrichten<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4273\"><a href=\"https:\/\/spcstuttgart.de\/de\/kontakt\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f9c471 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f9c471\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14fadf0\" data-id=\"14fadf0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7822c5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7822c5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-92a239f\" data-id=\"92a239f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fa81ce elementor-widget elementor-widget-heading\" data-id=\"9fa81ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/spcstuttgart.de\/de\/impressum\/\">Impressum<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e9120dc\" data-id=\"e9120dc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caec417 elementor-widget elementor-widget-heading\" data-id=\"caec417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/spcstuttgart.de\/de\/datenschutzerklarung\/\">Datenschutz<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b2dcf5 elementor-widget elementor-widget-heading\" data-id=\"8b2dcf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Serbisch-Orthodoxe Kirche Stuttgart. Alle Rechte vorbehalten.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u0411\u043e\u0433\u043e\u0441\u043b\u0443\u0436\u0435\u045a\u0430 \u0414\u043e\u0431\u0440\u043e\u0442\u0432\u043e\u0440\u043d\u0438 \u0440\u0430\u0434 \u201e\u0422\u0430\u0434\u0430 \u045b\u0435 \u0440\u0435\u045b\u0438 \u0426\u0430\u0440 \u043e\u043d\u0438\u043c\u0430 \u0448\u0442\u043e \u043c\u0443 \u0441\u0442\u043e\u0458\u0435 \u0441\u0430 \u0434\u0435\u0441\u043d\u0435 \u0441\u0442\u0440\u0430\u043d\u0435: \u0425\u043e\u0434\u0438\u0442\u0435 \u0431\u043b\u0430\u0433\u043e\u0441\u043b\u043e\u0432\u0435\u043d\u0438 \u041e\u0446\u0430 \u043c\u043e\u0458\u0435\u0433\u0430; \u043f\u0440\u0438\u043c\u0438\u0442\u0435 \u0426\u0430\u0440\u0441\u0442\u0432\u043e \u043a\u043e\u0458\u0435 \u0432\u0430\u043c \u0458\u0435 \u043f\u0440\u0438\u043f\u0440\u0435\u043c\u0459\u0435\u043d\u043e \u043e\u0434 \u043f\u043e\u0441\u0442\u0430\u045a\u0430 \u0441\u0432\u0438\u0458\u0435\u0442\u0430. \u0408\u0435\u0440 \u043e\u0433\u043b\u0430\u0434\u045a\u0435\u0445, \u0438 \u0434\u0430\u0434\u043e\u0441\u0442\u0435 \u043c\u0438 \u0434\u0430 \u0458\u0435\u0434\u0435\u043c; \u043e\u0436\u0435\u0434\u045a\u0435\u0445, \u0438 \u043d\u0430\u043f\u043e\u0458\u0438\u0441\u0442\u0435 \u043c\u0435; \u0441\u0442\u0440\u0430\u043d\u0430\u0446 \u0431\u0438\u0458\u0430\u0445, \u0438 \u043f\u0440\u0438\u043c\u0438\u0441\u0442\u0435 \u043c\u0435; \u041d\u0430\u0433 \u0431\u0438\u0458\u0430\u0445, \u0438 \u043e\u0434\u0458\u0435\u043d\u0443\u0441\u0442\u0435 \u043c\u0435; \u0431\u043e\u043b\u0435\u0441\u0442\u0430\u043d \u0431\u0438\u0458\u0430\u0445 \u0438 \u043f\u043e\u0441\u0458\u0435\u0442\u0438\u0441\u0442\u0435 \u043c\u0435; \u0443 \u0442\u0430\u043c\u043d\u0438\u0446\u0438 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"disabled","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3905","page","type-page","status-publish","hentry"],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/comments?post=3905"}],"version-history":[{"count":16,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3905\/revisions"}],"predecessor-version":[{"id":14066,"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/pages\/3905\/revisions\/14066"}],"wp:attachment":[{"href":"https:\/\/spcstuttgart.de\/de\/wp-json\/wp\/v2\/media?parent=3905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}